{"id":2409,"count":1,"description":"","link":"https:\/\/sailrivercafe.com\/de\/tag\/philippsbourg\/","name":"Philippsbourg","slug":"philippsbourg","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Philippsbourg Archives - sailrivercafe.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sailrivercafe.com\/de\/tag\/philippsbourg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Philippsbourg Archives - sailrivercafe.com\" \/>\n<meta property=\"og:site_name\" content=\"sailrivercafe.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/en\\\/tag\\\/philippsbourg\\\/\",\"url\":\"https:\\\/\\\/sailrivercafe.com\\\/en\\\/tag\\\/philippsbourg\\\/\",\"name\":\"Philippsbourg Archives - sailrivercafe.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/en\\\/tag\\\/philippsbourg\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/en\\\/tag\\\/philippsbourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Philippsbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/\",\"name\":\"sailrivercafe.com\",\"description\":\"Sailing blog - Karin and Holger Binz sailing the Rivercafe\",\"publisher\":{\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#\\\/schema\\\/person\\\/2a6d915689c5e5de6db1ea302fb3d852\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#\\\/schema\\\/person\\\/2a6d915689c5e5de6db1ea302fb3d852\",\"name\":\"Sailrivercafe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\",\"url\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\",\"contentUrl\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\",\"width\":673,\"height\":276,\"caption\":\"Sailrivercafe\"},\"logo\":{\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Philippsbourg Archives - sailrivercafe.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sailrivercafe.com\/de\/tag\/philippsbourg\/","og_locale":"de_DE","og_type":"article","og_title":"Philippsbourg Archives - sailrivercafe.com","og_site_name":"sailrivercafe.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sailrivercafe.com\/en\/tag\/philippsbourg\/","url":"https:\/\/sailrivercafe.com\/en\/tag\/philippsbourg\/","name":"Philippsbourg Archives - sailrivercafe.com","isPartOf":{"@id":"https:\/\/sailrivercafe.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/sailrivercafe.com\/en\/tag\/philippsbourg\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/sailrivercafe.com\/en\/tag\/philippsbourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sailrivercafe.com\/de\/"},{"@type":"ListItem","position":2,"name":"Philippsbourg"}]},{"@type":"WebSite","@id":"https:\/\/sailrivercafe.com\/de\/#website","url":"https:\/\/sailrivercafe.com\/de\/","name":"sailrivercafe.com","description":"Sailing blog - Karin and Holger Binz sailing the Rivercafe","publisher":{"@id":"https:\/\/sailrivercafe.com\/de\/#\/schema\/person\/2a6d915689c5e5de6db1ea302fb3d852"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sailrivercafe.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":["Person","Organization"],"@id":"https:\/\/sailrivercafe.com\/de\/#\/schema\/person\/2a6d915689c5e5de6db1ea302fb3d852","name":"Sailrivercafe","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png","url":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png","contentUrl":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png","width":673,"height":276,"caption":"Sailrivercafe"},"logo":{"@id":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png"}}]}},"_links":{"self":[{"href":"https:\/\/sailrivercafe.com\/de\/wp-json\/wp\/v2\/tags\/2409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sailrivercafe.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sailrivercafe.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sailrivercafe.com\/de\/wp-json\/wp\/v2\/posts?tags=2409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}