{"id":3119,"count":1,"description":"","link":"https:\/\/sailrivercafe.com\/en\/tag\/klondike\/","name":"","slug":"klondike","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sailrivercafe.com\/en\/tag\/klondike\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives -\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/tag\\\/klondike\\\/\",\"url\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/tag\\\/klondike\\\/\",\"name\":\"Archives -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#website\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/\",\"name\":\"sailrivercafe.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#\\\/schema\\\/person\\\/2a6d915689c5e5de6db1ea302fb3d852\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/de\\\/#\\\/schema\\\/person\\\/2a6d915689c5e5de6db1ea302fb3d852\",\"name\":\"Sailrivercafe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\",\"url\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\",\"contentUrl\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\",\"width\":673,\"height\":276,\"caption\":\"Sailrivercafe\"},\"logo\":{\"@id\":\"https:\\\/\\\/sailrivercafe.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sailrivercafe.com\/en\/tag\/klondike\/","og_locale":"en_GB","og_type":"article","og_title":"Archives -","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sailrivercafe.com\/de\/tag\/klondike\/","url":"https:\/\/sailrivercafe.com\/de\/tag\/klondike\/","name":"Archives -","isPartOf":{"@id":"https:\/\/sailrivercafe.com\/de\/#website"},"inLanguage":"en-GB"},{"@type":"WebSite","@id":"https:\/\/sailrivercafe.com\/de\/#website","url":"https:\/\/sailrivercafe.com\/de\/","name":"sailrivercafe.com","description":"","publisher":{"@id":"https:\/\/sailrivercafe.com\/de\/#\/schema\/person\/2a6d915689c5e5de6db1ea302fb3d852"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sailrivercafe.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/sailrivercafe.com\/de\/#\/schema\/person\/2a6d915689c5e5de6db1ea302fb3d852","name":"Sailrivercafe","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png","url":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png","contentUrl":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png","width":673,"height":276,"caption":"Sailrivercafe"},"logo":{"@id":"https:\/\/sailrivercafe.com\/wp-content\/uploads\/2021\/01\/Logo.png"}}]}},"_links":{"self":[{"href":"https:\/\/sailrivercafe.com\/en\/wp-json\/wp\/v2\/tags\/3119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sailrivercafe.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sailrivercafe.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sailrivercafe.com\/en\/wp-json\/wp\/v2\/posts?tags=3119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}